{"id":16582,"date":"2020-06-01T14:40:59","date_gmt":"2020-06-01T21:40:59","guid":{"rendered":"https:\/\/rolamixinc.wpcomstaging.com\/?p=16582"},"modified":"2020-06-01T14:40:59","modified_gmt":"2020-06-01T21:40:59","slug":"eden-munoz-de-calibre-50-en-aislamiento-por-posible-contagio-de-covid-19","status":"publish","type":"post","link":"https:\/\/rolamix.com\/espectaculos\/eden-munoz-de-calibre-50-en-aislamiento-por-posible-contagio-de-covid-19\/","title":{"rendered":"Eden Mu\u00f1oz de Calibre 50 en aislamiento por posible contagio de COVID-19"},"content":{"rendered":"\n<p>La actual pandemia se ha propagado a m\u00e1s de 6 millones de contagiados y M\u00e9xico no escapa de la lista de los pa\u00edses que han tenido una gran cantidad de afectados. Por lo que, <strong>nadie est\u00e1 exento de sufrir de adquirir este peligroso virus<\/strong> en su cuerpo. Es por ello que se sigue pidiendo a los ciudadanos tomen las medidas de higiene necesarias para evitar contagiarse o que se queden en casa en la medida de lo posible.<\/p>\n\n\n\n<p>Sin embargo, siendo bastante dif\u00edcil de controlar todo esto, siguen estando expuestas muchas personas al <strong>peligro de contraer COVID-19<\/strong>. Recientemente, una noticia ha alarmado a integrantes de reconocidas agrupaciones musicales del regional mexicano.<\/p>\n\n\n\n<p>Y es que, se ha conocido a trav\u00e9s de algunos sitios noticiosos de internet que, <strong>varios colaboradores del estudio de grabaci\u00f3n de Andaluz Music habr\u00edan sido diagnosticados como positivos casos de COVID-19<\/strong>. <\/p>\n\n\n\n<p>Asimismo, se inform\u00f3 que <strong>Ed\u00e9n Mu\u00f1oz de Calibre 50 presenta s\u00edntomas de tener el virus<\/strong> y que por ello, se encuentra en aislamiento total. Sin embargo, no se ha confirmado que se manejen resultados de la respectiva prueba que confirme esta informaci\u00f3n.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fvideorolavroficial%2Fphotos%2Fa.313468992017809%2F3357498504281494%2F%3Ftype%3D3&amp;width=500\" width=\"500\" height=\"708\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowtransparency=\"true\" allow=\"encrypted-media\"><\/iframe>\n\n\n\n<p>Por otro lado, <strong>tambi\u00e9n se esta hablando de que La S\u00e9ptima Banda tendr\u00eda un posible caso<\/strong> pero, tampoco lo han confirmado, ni precisado exactamente qui\u00e9n es. De ser as\u00ed, seguramente los muchachos de la conocida agrupaci\u00f3n estar\u00edan tomando las medidas necesarias para corroborar que est\u00e1n bien y seguir el debido aislamiento. Tal como desde ya, todos los trabajadores de Andaluz Music, seguramente lo est\u00e1n haciendo y los m\u00fasicos que habr\u00edan pasado recientemente por dichas instalaciones, de ser cierta la informaci\u00f3n que circula.<\/p>\n\n\n\n<p>Quiz\u00e1s tambi\u00e9n te interese leer: <a href=\"https:\/\/rolamix.com\/espectaculos\/pausa-el-nuevo-trabajo-musical-de-ricky-martin\/\">\u201cPausa\u201d, El Nuevo Trabajo Musical De Ricky Martin<\/a><\/p>\n\n\n\n<p>Por los momentos, se contin\u00faa a la espera de que en las fuentes oficiales de las respectivas agrupaciones musicales, se hable sobre lo que est\u00e1 ocurriendo con respecto a la salud de los integrantes. Misma acci\u00f3n que podr\u00eda tomar en las pr\u00f3ximas horas la casa productora para aclarar mejor lo que est\u00e1 sucediendo con sus trabajadores y el <strong>estado de salud en el que se encuentran los afectados<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actual pandemia se ha propagado a m\u00e1s de 6 millones de contagiados y M\u00e9xico no escapa de la lista de los pa\u00edses que han tenido una gran cantidad de afectados. Por lo que, nadie est\u00e1 exento de sufrir de adquirir este peligroso virus en su cuerpo. Es por ello que se sigue pidiendo a [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":16585,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2260,12,1895,619,230],"class_list":["post-16582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-andaluz-music","tag-calibre-50","tag-covid-19","tag-eden-munoz","tag-la-septima-banda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/posts\/16582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/comments?post=16582"}],"version-history":[{"count":0,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/posts\/16582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/media\/16585"}],"wp:attachment":[{"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/media?parent=16582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/categories?post=16582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/tags?post=16582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}