{"id":16641,"date":"2020-06-02T19:46:51","date_gmt":"2020-06-03T02:46:51","guid":{"rendered":"https:\/\/rolamixinc.wpcomstaging.com\/?p=16641"},"modified":"2020-06-02T19:46:51","modified_gmt":"2020-06-03T02:46:51","slug":"a-menos-de-un-ano-de-su-matrimonio-chiquis-rivera-y-lorenzo-mendez-se-separan","status":"publish","type":"post","link":"https:\/\/rolamix.com\/espectaculos\/a-menos-de-un-ano-de-su-matrimonio-chiquis-rivera-y-lorenzo-mendez-se-separan\/","title":{"rendered":"A menos de un a\u00f1o de su matrimonio Chiquis Rivera y Lorenzo M\u00e9ndez se separan"},"content":{"rendered":"\n<p>Finalmente, luego de tantos rumores circulando en internet sobre una supuesta infidelidad por parte de <strong>Lorenzo M\u00e9ndez<\/strong> y posibles problemas en el matrimonio de esta pol\u00e9mica pareja de la far\u00e1ndula mexicana, <strong>Chiquis Rivera<\/strong> ha dejado claro en una entrevista virtual para el programa Hoy, que efectivamente ella y su marido <strong>se encuentran d\u00e1ndose un espacio<\/strong>.<\/p>\n\n\n\n<p>Tras algunas semanas de difundirse diferentes conjeturas por ciertos eventos en torno a la pareja y hablarse incluso, de una infidelidad por parte de Lorenzo M\u00e9ndez, luego desmentida por la propia mujer con la cual se le relacion\u00f3, ahora lo que s\u00ed es cierto, es que la pareja est\u00e1 separada.<\/p>\n\n\n\n<p>Chiquis accedi\u00f3 a hablar sobre su vida personal recientemente, aunque el objetivo que la ha concentrado por estos d\u00edas es el lanzamiento de su <strong>tercera producci\u00f3n discogr\u00e1fica titulada Playlist<\/strong>. En la entrevista la hija de la fallecida Diva de la banda, Jenni Rivera, <strong>coment\u00f3 que efectivamente aunque hab\u00eda amor y cari\u00f1o<\/strong> entre ella y su aun esposo, <strong>se encontraban por el momento d\u00e1ndose un espacio<\/strong>.<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"532\" height=\"299\" src=\"https:\/\/www.youtube.com\/embed\/AEJqoBIQiK0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe>\n\n\n\n<p>Pero adem\u00e1s de hablar sobre la separaci\u00f3n de la cual a\u00fan no afirm\u00f3 que fuese definitiva, tambi\u00e9n se le pregunt\u00f3 sobre la tan mencionada infidelidad de la que se ha estado especulando y sobre esto, Chiquis tambi\u00e9n acept\u00f3 responder porque seg\u00fan dijo, se le estaba preguntando con un debido respeto que agradec\u00eda. La cantante dijo que por ahora, <strong>no ha habido infidelidad<\/strong> de ninguna de las partes y que esa no es la raz\u00f3n del distanciamiento.<\/p>\n\n\n\n<p>Quiz\u00e1s tambi\u00e9n te interese leer: <a href=\"https:\/\/rolamix.com\/espectaculos\/becky-g-y-chiquis-rivera-lanzan-un-clasico-de-country\/\">Becky G Y Chiquis Rivera, Lanzan Un Cl\u00e1sico De Country<\/a><\/p>\n\n\n\n<p>Por su parte, <strong>Lorenzo M\u00e9ndez<\/strong> solo ha hablado de la separaci\u00f3n a trav\u00e9s de sus historias de Instagram donde pidi\u00f3 a la gente respeto porque nadie sino \u00e9l y su esposa, conoc\u00edan lo que realmente pasaba entre ellos. Por lo tanto, <strong>se limit\u00f3 a pedir oraciones<\/strong> para cada uno, as\u00ed como para su matrimonio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalmente, luego de tantos rumores circulando en internet sobre una supuesta infidelidad por parte de Lorenzo M\u00e9ndez y posibles problemas en el matrimonio de esta pol\u00e9mica pareja de la far\u00e1ndula mexicana, Chiquis Rivera ha dejado claro en una entrevista virtual para el programa Hoy, que efectivamente ella y su marido se encuentran d\u00e1ndose un espacio. [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":16643,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[162,1160,2240,72,1523,2267],"class_list":["post-16641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-chiquis-rivera","tag-infidelidad","tag-lorenzo-mendez-2","tag-nuevo-disco","tag-playlist","tag-separacion"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/posts\/16641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/comments?post=16641"}],"version-history":[{"count":0,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/posts\/16641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/media\/16643"}],"wp:attachment":[{"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/media?parent=16641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/categories?post=16641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rolamix.com\/espectaculos\/wp-json\/wp\/v2\/tags?post=16641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}